{"id":62520,"date":"2023-05-23T13:03:49","date_gmt":"2023-05-23T11:03:49","guid":{"rendered":"https:\/\/www.techbarcelona.com\/event\/real-estate-challenge\/"},"modified":"2023-05-23T17:30:35","modified_gmt":"2023-05-23T15:30:35","slug":"real-estate-challenge","status":"publish","type":"event","link":"https:\/\/www.techbarcelona.com\/ca\/event\/real-estate-challenge\/","title":{"rendered":"Real Estate Challenge"},"content":{"rendered":"","protected":false},"featured_media":62511,"template":"","class_list":["post-62520","event","type-event","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Real Estate Challenge - Tech Barcelona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.techbarcelona.com\/ca\/event\/real-estate-challenge\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Real Estate Challenge - Tech Barcelona\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.techbarcelona.com\/ca\/event\/real-estate-challenge\/\" \/>\n<meta property=\"og:site_name\" content=\"Tech Barcelona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BarcelonaTechCity\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-23T15:30:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.techbarcelona.com\/wp-content\/uploads\/image-706.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@bcntechcity\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.techbarcelona.com\\\/ca\\\/event\\\/real-estate-challenge\\\/\",\"url\":\"https:\\\/\\\/www.techbarcelona.com\\\/ca\\\/event\\\/real-estate-challenge\\\/\",\"name\":\"Real Estate Challenge - Tech Barcelona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.techbarcelona.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.techbarcelona.com\\\/ca\\\/event\\\/real-estate-challenge\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.techbarcelona.com\\\/ca\\\/event\\\/real-estate-challenge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.techbarcelona.com\\\/wp-content\\\/uploads\\\/image-706.jpeg\",\"datePublished\":\"2023-05-23T11:03:49+00:00\",\"dateModified\":\"2023-05-23T15:30:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.techbarcelona.com\\\/ca\\\/event\\\/real-estate-challenge\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.techbarcelona.com\\\/ca\\\/event\\\/real-estate-challenge\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.techbarcelona.com\\\/ca\\\/event\\\/real-estate-challenge\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.techbarcelona.com\\\/wp-content\\\/uploads\\\/image-706.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.techbarcelona.com\\\/wp-content\\\/uploads\\\/image-706.jpeg\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.techbarcelona.com\\\/ca\\\/event\\\/real-estate-challenge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.techbarcelona.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/www.techbarcelona.com\\\/ca\\\/event\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Real Estate Challenge\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.techbarcelona.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.techbarcelona.com\\\/ca\\\/\",\"name\":\"Tech Barcelona\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.techbarcelona.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.techbarcelona.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.techbarcelona.com\\\/ca\\\/#organization\",\"name\":\"Tech Barcelona\",\"url\":\"https:\\\/\\\/www.techbarcelona.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.techbarcelona.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.techbarcelona.com\\\/wp-content\\\/uploads\\\/logo-tech-bcn-black.png\",\"contentUrl\":\"https:\\\/\\\/www.techbarcelona.com\\\/wp-content\\\/uploads\\\/logo-tech-bcn-black.png\",\"width\":347,\"height\":90,\"caption\":\"Tech Barcelona\"},\"image\":{\"@id\":\"https:\\\/\\\/www.techbarcelona.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/BarcelonaTechCity\",\"https:\\\/\\\/x.com\\\/bcntechcity\",\"https:\\\/\\\/www.instagram.com\\\/bcntechcity\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/barcelona-tech-city\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCKX-ZX0pM37GRtVNKgr4Rxg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Real Estate Challenge - Tech Barcelona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.techbarcelona.com\/ca\/event\/real-estate-challenge\/","og_locale":"ca_ES","og_type":"article","og_title":"Real Estate Challenge - Tech Barcelona","og_url":"https:\/\/www.techbarcelona.com\/ca\/event\/real-estate-challenge\/","og_site_name":"Tech Barcelona","article_publisher":"https:\/\/www.facebook.com\/BarcelonaTechCity","article_modified_time":"2023-05-23T15:30:35+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/www.techbarcelona.com\/wp-content\/uploads\/image-706.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@bcntechcity","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.techbarcelona.com\/ca\/event\/real-estate-challenge\/","url":"https:\/\/www.techbarcelona.com\/ca\/event\/real-estate-challenge\/","name":"Real Estate Challenge - Tech Barcelona","isPartOf":{"@id":"https:\/\/www.techbarcelona.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.techbarcelona.com\/ca\/event\/real-estate-challenge\/#primaryimage"},"image":{"@id":"https:\/\/www.techbarcelona.com\/ca\/event\/real-estate-challenge\/#primaryimage"},"thumbnailUrl":"https:\/\/www.techbarcelona.com\/wp-content\/uploads\/image-706.jpeg","datePublished":"2023-05-23T11:03:49+00:00","dateModified":"2023-05-23T15:30:35+00:00","breadcrumb":{"@id":"https:\/\/www.techbarcelona.com\/ca\/event\/real-estate-challenge\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.techbarcelona.com\/ca\/event\/real-estate-challenge\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.techbarcelona.com\/ca\/event\/real-estate-challenge\/#primaryimage","url":"https:\/\/www.techbarcelona.com\/wp-content\/uploads\/image-706.jpeg","contentUrl":"https:\/\/www.techbarcelona.com\/wp-content\/uploads\/image-706.jpeg","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.techbarcelona.com\/ca\/event\/real-estate-challenge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.techbarcelona.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/www.techbarcelona.com\/ca\/event\/"},{"@type":"ListItem","position":3,"name":"Real Estate Challenge"}]},{"@type":"WebSite","@id":"https:\/\/www.techbarcelona.com\/ca\/#website","url":"https:\/\/www.techbarcelona.com\/ca\/","name":"Tech Barcelona","description":"","publisher":{"@id":"https:\/\/www.techbarcelona.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.techbarcelona.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.techbarcelona.com\/ca\/#organization","name":"Tech Barcelona","url":"https:\/\/www.techbarcelona.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.techbarcelona.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.techbarcelona.com\/wp-content\/uploads\/logo-tech-bcn-black.png","contentUrl":"https:\/\/www.techbarcelona.com\/wp-content\/uploads\/logo-tech-bcn-black.png","width":347,"height":90,"caption":"Tech Barcelona"},"image":{"@id":"https:\/\/www.techbarcelona.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BarcelonaTechCity","https:\/\/x.com\/bcntechcity","https:\/\/www.instagram.com\/bcntechcity\/","https:\/\/www.linkedin.com\/company\/barcelona-tech-city\/","https:\/\/www.youtube.com\/channel\/UCKX-ZX0pM37GRtVNKgr4Rxg"]}]}},"_links":{"self":[{"href":"https:\/\/www.techbarcelona.com\/ca\/wp-json\/wp\/v2\/event\/62520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.techbarcelona.com\/ca\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.techbarcelona.com\/ca\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.techbarcelona.com\/ca\/wp-json\/wp\/v2\/media\/62511"}],"wp:attachment":[{"href":"https:\/\/www.techbarcelona.com\/ca\/wp-json\/wp\/v2\/media?parent=62520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}