{"id":71541,"date":"2024-05-13T13:16:01","date_gmt":"2024-05-13T11:16:01","guid":{"rendered":"https:\/\/www.techbarcelona.com\/posting\/citcea-upc-y-biyiud-colaboran-en-el-desarrollo-de-un-innovador-modelo-para-mejorar-la-flexibilidad-de-la-demanda-electrica-residencial-mediante-machine-learning\/"},"modified":"2024-05-13T13:16:01","modified_gmt":"2024-05-13T11:16:01","slug":"citcea-upc-y-biyiud-colaboran-en-el-desarrollo-de-un-innovador-modelo-para-mejorar-la-flexibilidad-de-la-demanda-electrica-residencial-mediante-machine-learning","status":"publish","type":"posting","link":"https:\/\/www.techbarcelona.com\/ca\/posting\/citcea-upc-y-biyiud-colaboran-en-el-desarrollo-de-un-innovador-modelo-para-mejorar-la-flexibilidad-de-la-demanda-electrica-residencial-mediante-machine-learning\/","title":{"rendered":"CITCEA-UPC y Biyiud colaboran en el desarrollo de un innovador modelo para mejorar la flexibilidad de la demanda el\u00e9ctrica residencial mediante Machine Learning"},"content":{"rendered":"<p><span style=\"font-size: 16px;\">Con la financiaci\u00f3n del Programa de Apoyo a los Digital Innovation Hubs (PADIH), el <a href=\"https:\/\/www.citcea.upc.edu\/ca\" target=\"_blank\" rel=\"noreferrer noopener\">Centre d&#8217;Innovaci\u00f3 Tecnol\u00f2gica en Convertidors Est\u00e0tics i Accionaments (CITCEA)<\/a> y Biyiud han comenzado una emocionante colaboraci\u00f3n para desarrollar una innovadora capa tecnol\u00f3gica de Machine Learning destinada a mejorar la flexibilidad de la demanda el\u00e9ctrica residencial. Esta alianza combina la experiencia en investigaci\u00f3n del CITCEA-UPC\u00a0con la agilidad y el enfoque empresarial para la sostenibilidad de Biyiud.<\/span><\/p>\n<p><span style=\"font-size: 16px;\">El proyecto, de 12 meses de duraci\u00f3n, es dirigido por parte del CITCEA por el Catedr\u00e1tico Andreas Sumper, y por parte de Biyiud por su CEO el Dr. Manuel Villa-Arrieta. Su objetivo es mejorar el actual sistema de an\u00e1lisis de datos que utiliza la startup para incentivar la respuesta activa de la demanda el\u00e9ctrica residencial a favor del incremento en el consumo de energ\u00eda renovable. Esta soluci\u00f3n contribuir\u00e1 a la eficiencia energ\u00e9tica y la sostenibilidad del sistema el\u00e9ctrico.<\/span><\/p>\n<p><span style=\"font-size: 16px;\"><strong>La propuesta de Biyiud: Sostenibilidad a trav\u00e9s de la energ\u00eda<\/strong><\/span><\/p>\n<p><span style=\"font-size: 16px;\">A trav\u00e9s de la App de Biyiud los consumidores el\u00e9ctricos residenciales pueden obtener puntos de EcoValor por seguir recomendaciones diarias de consumo el\u00e9ctrico renovable, los cuales pueden ser recibidos en programas de fidelizaci\u00f3n de marcas sostenibles. Como resultado, se reducen las emisiones de CO<sub>2<\/sub> del sistema el\u00e9ctrico y estas empresas ganan EcoReputaci\u00f3n y nuevas ventas.<\/span><\/p>\n<p><span style=\"font-size: 16px;\">El concepto del proyecto propuesto por Biyiud se centra en el uso de lecturas provenientes de los Smart Meters para, a trav\u00e9s de avanzadas t\u00e9cnicas de Machine Learning, incrementar el valor de los datos recopilados. Esta mejora en la informaci\u00f3n permite personalizar las recomendaciones de consumo el\u00e9ctrico, adapt\u00e1ndolas a las caracter\u00edsticas espec\u00edficas de cada usuario, como sus h\u00e1bitos de consumo, la utilizaci\u00f3n de dispositivos el\u00e9ctricos y la gesti\u00f3n de la energ\u00eda generada por sistemas de autoconsumo, incluyendo la fotovoltaica y veh\u00edculos el\u00e9ctricos.<\/span><\/p>\n<p><span style=\"font-size: 16px;\"><strong>A qu\u00e9 hora encender la lavadora para ser sostenibles<\/strong><\/span><\/p>\n<p><span style=\"font-size: 16px;\">Para conseguir aprovechar al m\u00e1ximo las energ\u00edas solar y e\u00f3lica y reducir las emisiones de CO<sub>2<\/sub> es necesario que el consumo el\u00e9ctrico est\u00e9 alineado a la presencia de estas fuentes renovables. Pero este ejercicio, llamado flexibilidad de la demanda, no es f\u00e1cil en los hogares porque no se dispone ni de las herramientas ni de los incentivos adecuados para optimizar el consumo de energ\u00eda verde.<\/span><\/p>\n<p><span style=\"font-size: 16px;\">La iniciativa entre Biyiud y el CITCEA-UPC busca dar soluci\u00f3n a este problema incluyendo a las personas de forma sencilla al funcionamiento del sistema el\u00e9ctrico. Mejorando, a trav\u00e9s de una App y sin la necesidad de instalar nuevos dispositivos, la capacidad de los hogares para ajustar su consumo de energ\u00eda el\u00e9ctrica en respuesta al incentivo de obtener puntos de EcoValor que dan acceso a una comunidad de marcas que trabajan por la sostenibilidad.<\/span><\/p>\n<p><span style=\"font-size: 16px;\"><strong>Sobre Biyiud y el CITCEA-UPC<\/strong><\/span><\/p>\n<p><span style=\"font-size: 16px;\">CITCEA-UPC es un centro de investigaci\u00f3n e innovaci\u00f3n tecnol\u00f3gica en el \u00e1mbito de la energ\u00eda el\u00e9ctrica y la electr\u00f3nica de potencia fundado en 2001. Pertenece a la Universitat Polit\u00e8cnica de Catalunya, BarcelonaTech. Es miembro de la red TECNIO D\u2019ACCIO (Generalitat de Catalunya) y est\u00e1 reconocido como Grup de Recerca por parte de AGAUR, Generalitat de Catalunya.<\/span><\/p>\n<p><span style=\"font-size: 16px;\">Biyiud es una startup fundada en Barcelona en 2021 con el prop\u00f3sito de convertir la sostenibilidad en riqueza. Hace parte del programa EmprenUPC y del Cl\u00faster de l&#8217;Energia Eficient de Catalunya (CEEC). Ha participado en los programas CleanTech Camp de EIT Innoenergy, Catalonia Exponencial Leaders de ACCI\u00d3, Tech4Climate de Ship2B Foundation y actualmente en Google Cloud for Startups.<\/span><\/p>\n<p><span style=\"font-size: 16px;\">Tambi\u00e9n puedes leer la noticia emitida por la Universidad Polit\u00e9cnica de Catalunya &#8211; BarcelonaTech (UPC): https:\/\/www.upc.edu\/ca\/sala-de-premsa\/noticies\/desenvolupen-nou-model-per-millorar-flexibilitat-demanda-electrica-machine-learning<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la financiaci\u00f3n del Programa de Apoyo a los Digital Innovation Hubs (PADIH), el Centre d&#8217;Innovaci\u00f3 Tecnol\u00f2gica en Convertidors Est\u00e0tics i Accionaments (CITCEA) y Biyiud han comenzado una emocionante colaboraci\u00f3n para desarrollar una innovadora capa tecnol\u00f3gica de Machine Learning destinada a mejorar la flexibilidad de la demanda el\u00e9ctrica residencial. Esta [&hellip;]<\/p>\n","protected":false},"template":"","class_list":["post-71541","posting","type-posting","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CITCEA-UPC y Biyiud colaboran en el desarrollo de un innovador modelo para mejorar la flexibilidad de la demanda el\u00e9ctrica residencial mediante Machine Learning - Tech Barcelona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.techbarcelona.com\/ca\/posting\/citcea-upc-y-biyiud-colaboran-en-el-desarrollo-de-un-innovador-modelo-para-mejorar-la-flexibilidad-de-la-demanda-electrica-residencial-mediante-machine-learning\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CITCEA-UPC y Biyiud colaboran en el desarrollo de un innovador modelo para mejorar la flexibilidad de la demanda el\u00e9ctrica residencial mediante Machine Learning - Tech Barcelona\" \/>\n<meta property=\"og:description\" content=\"Con la financiaci\u00f3n del Programa de Apoyo a los Digital Innovation Hubs (PADIH), el Centre d&#8217;Innovaci\u00f3 Tecnol\u00f2gica en Convertidors Est\u00e0tics i Accionaments (CITCEA) y Biyiud han comenzado una emocionante colaboraci\u00f3n para desarrollar una innovadora capa tecnol\u00f3gica de Machine Learning destinada a mejorar la flexibilidad de la demanda el\u00e9ctrica residencial. Esta [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.techbarcelona.com\/ca\/posting\/citcea-upc-y-biyiud-colaboran-en-el-desarrollo-de-un-innovador-modelo-para-mejorar-la-flexibilidad-de-la-demanda-electrica-residencial-mediante-machine-learning\/\" \/>\n<meta property=\"og:site_name\" content=\"Tech Barcelona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BarcelonaTechCity\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@bcntechcity\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.techbarcelona.com\\\/ca\\\/posting\\\/citcea-upc-y-biyiud-colaboran-en-el-desarrollo-de-un-innovador-modelo-para-mejorar-la-flexibilidad-de-la-demanda-electrica-residencial-mediante-machine-learning\\\/\",\"url\":\"https:\\\/\\\/www.techbarcelona.com\\\/ca\\\/posting\\\/citcea-upc-y-biyiud-colaboran-en-el-desarrollo-de-un-innovador-modelo-para-mejorar-la-flexibilidad-de-la-demanda-electrica-residencial-mediante-machine-learning\\\/\",\"name\":\"CITCEA-UPC y Biyiud colaboran en el desarrollo de un innovador modelo para mejorar la flexibilidad de la demanda el\u00e9ctrica residencial mediante Machine Learning - Tech Barcelona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.techbarcelona.com\\\/ca\\\/#website\"},\"datePublished\":\"2024-05-13T11:16:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.techbarcelona.com\\\/ca\\\/posting\\\/citcea-upc-y-biyiud-colaboran-en-el-desarrollo-de-un-innovador-modelo-para-mejorar-la-flexibilidad-de-la-demanda-electrica-residencial-mediante-machine-learning\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.techbarcelona.com\\\/ca\\\/posting\\\/citcea-upc-y-biyiud-colaboran-en-el-desarrollo-de-un-innovador-modelo-para-mejorar-la-flexibilidad-de-la-demanda-electrica-residencial-mediante-machine-learning\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.techbarcelona.com\\\/ca\\\/posting\\\/citcea-upc-y-biyiud-colaboran-en-el-desarrollo-de-un-innovador-modelo-para-mejorar-la-flexibilidad-de-la-demanda-electrica-residencial-mediante-machine-learning\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.techbarcelona.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Postings\",\"item\":\"https:\\\/\\\/www.techbarcelona.com\\\/ca\\\/posting\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CITCEA-UPC y Biyiud colaboran en el desarrollo de un innovador modelo para mejorar la flexibilidad de la demanda el\u00e9ctrica residencial mediante Machine Learning\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.techbarcelona.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.techbarcelona.com\\\/ca\\\/\",\"name\":\"Tech Barcelona\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.techbarcelona.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.techbarcelona.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.techbarcelona.com\\\/ca\\\/#organization\",\"name\":\"Tech Barcelona\",\"url\":\"https:\\\/\\\/www.techbarcelona.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.techbarcelona.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.techbarcelona.com\\\/wp-content\\\/uploads\\\/logo-tech-bcn-black.png\",\"contentUrl\":\"https:\\\/\\\/www.techbarcelona.com\\\/wp-content\\\/uploads\\\/logo-tech-bcn-black.png\",\"width\":347,\"height\":90,\"caption\":\"Tech Barcelona\"},\"image\":{\"@id\":\"https:\\\/\\\/www.techbarcelona.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/BarcelonaTechCity\",\"https:\\\/\\\/x.com\\\/bcntechcity\",\"https:\\\/\\\/www.instagram.com\\\/bcntechcity\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/barcelona-tech-city\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCKX-ZX0pM37GRtVNKgr4Rxg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CITCEA-UPC y Biyiud colaboran en el desarrollo de un innovador modelo para mejorar la flexibilidad de la demanda el\u00e9ctrica residencial mediante Machine Learning - Tech Barcelona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.techbarcelona.com\/ca\/posting\/citcea-upc-y-biyiud-colaboran-en-el-desarrollo-de-un-innovador-modelo-para-mejorar-la-flexibilidad-de-la-demanda-electrica-residencial-mediante-machine-learning\/","og_locale":"ca_ES","og_type":"article","og_title":"CITCEA-UPC y Biyiud colaboran en el desarrollo de un innovador modelo para mejorar la flexibilidad de la demanda el\u00e9ctrica residencial mediante Machine Learning - Tech Barcelona","og_description":"Con la financiaci\u00f3n del Programa de Apoyo a los Digital Innovation Hubs (PADIH), el Centre d&#8217;Innovaci\u00f3 Tecnol\u00f2gica en Convertidors Est\u00e0tics i Accionaments (CITCEA) y Biyiud han comenzado una emocionante colaboraci\u00f3n para desarrollar una innovadora capa tecnol\u00f3gica de Machine Learning destinada a mejorar la flexibilidad de la demanda el\u00e9ctrica residencial. Esta [&hellip;]","og_url":"https:\/\/www.techbarcelona.com\/ca\/posting\/citcea-upc-y-biyiud-colaboran-en-el-desarrollo-de-un-innovador-modelo-para-mejorar-la-flexibilidad-de-la-demanda-electrica-residencial-mediante-machine-learning\/","og_site_name":"Tech Barcelona","article_publisher":"https:\/\/www.facebook.com\/BarcelonaTechCity","twitter_card":"summary_large_image","twitter_site":"@bcntechcity","twitter_misc":{"Temps estimat de lectura":"3 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.techbarcelona.com\/ca\/posting\/citcea-upc-y-biyiud-colaboran-en-el-desarrollo-de-un-innovador-modelo-para-mejorar-la-flexibilidad-de-la-demanda-electrica-residencial-mediante-machine-learning\/","url":"https:\/\/www.techbarcelona.com\/ca\/posting\/citcea-upc-y-biyiud-colaboran-en-el-desarrollo-de-un-innovador-modelo-para-mejorar-la-flexibilidad-de-la-demanda-electrica-residencial-mediante-machine-learning\/","name":"CITCEA-UPC y Biyiud colaboran en el desarrollo de un innovador modelo para mejorar la flexibilidad de la demanda el\u00e9ctrica residencial mediante Machine Learning - Tech Barcelona","isPartOf":{"@id":"https:\/\/www.techbarcelona.com\/ca\/#website"},"datePublished":"2024-05-13T11:16:01+00:00","breadcrumb":{"@id":"https:\/\/www.techbarcelona.com\/ca\/posting\/citcea-upc-y-biyiud-colaboran-en-el-desarrollo-de-un-innovador-modelo-para-mejorar-la-flexibilidad-de-la-demanda-electrica-residencial-mediante-machine-learning\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.techbarcelona.com\/ca\/posting\/citcea-upc-y-biyiud-colaboran-en-el-desarrollo-de-un-innovador-modelo-para-mejorar-la-flexibilidad-de-la-demanda-electrica-residencial-mediante-machine-learning\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.techbarcelona.com\/ca\/posting\/citcea-upc-y-biyiud-colaboran-en-el-desarrollo-de-un-innovador-modelo-para-mejorar-la-flexibilidad-de-la-demanda-electrica-residencial-mediante-machine-learning\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.techbarcelona.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Postings","item":"https:\/\/www.techbarcelona.com\/ca\/posting\/"},{"@type":"ListItem","position":3,"name":"CITCEA-UPC y Biyiud colaboran en el desarrollo de un innovador modelo para mejorar la flexibilidad de la demanda el\u00e9ctrica residencial mediante Machine Learning"}]},{"@type":"WebSite","@id":"https:\/\/www.techbarcelona.com\/ca\/#website","url":"https:\/\/www.techbarcelona.com\/ca\/","name":"Tech Barcelona","description":"","publisher":{"@id":"https:\/\/www.techbarcelona.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.techbarcelona.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.techbarcelona.com\/ca\/#organization","name":"Tech Barcelona","url":"https:\/\/www.techbarcelona.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.techbarcelona.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.techbarcelona.com\/wp-content\/uploads\/logo-tech-bcn-black.png","contentUrl":"https:\/\/www.techbarcelona.com\/wp-content\/uploads\/logo-tech-bcn-black.png","width":347,"height":90,"caption":"Tech Barcelona"},"image":{"@id":"https:\/\/www.techbarcelona.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BarcelonaTechCity","https:\/\/x.com\/bcntechcity","https:\/\/www.instagram.com\/bcntechcity\/","https:\/\/www.linkedin.com\/company\/barcelona-tech-city\/","https:\/\/www.youtube.com\/channel\/UCKX-ZX0pM37GRtVNKgr4Rxg"]}]}},"_links":{"self":[{"href":"https:\/\/www.techbarcelona.com\/ca\/wp-json\/wp\/v2\/posting\/71541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.techbarcelona.com\/ca\/wp-json\/wp\/v2\/posting"}],"about":[{"href":"https:\/\/www.techbarcelona.com\/ca\/wp-json\/wp\/v2\/types\/posting"}],"wp:attachment":[{"href":"https:\/\/www.techbarcelona.com\/ca\/wp-json\/wp\/v2\/media?parent=71541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}