{"id":68745,"date":"2024-01-31T17:09:31","date_gmt":"2024-01-31T16:09:31","guid":{"rendered":"https:\/\/www.techbarcelona.com\/event\/mwc-open-innovation-challenge-2024-dl-15-febrer\/"},"modified":"2024-01-31T17:09:31","modified_gmt":"2024-01-31T16:09:31","slug":"mwc-open-innovation-challenge-2024-dl-15-febrer","status":"publish","type":"event","link":"https:\/\/www.techbarcelona.com\/en\/event\/mwc-open-innovation-challenge-2024-dl-15-febrer\/","title":{"rendered":"MWC Open Innovation Challenge 2024 (DL: 15 febrer)"},"content":{"rendered":"","protected":false},"featured_media":68743,"template":"","class_list":["post-68745","event","type-event","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MWC Open Innovation Challenge 2024 (DL: 15 febrer) - Tech Barcelona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.techbarcelona.com\/en\/event\/mwc-open-innovation-challenge-2024-dl-15-febrer\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MWC Open Innovation Challenge 2024 (DL: 15 febrer) - Tech Barcelona\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.techbarcelona.com\/en\/event\/mwc-open-innovation-challenge-2024-dl-15-febrer\/\" \/>\n<meta property=\"og:site_name\" content=\"Tech Barcelona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BarcelonaTechCity\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@bcntechcity\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.techbarcelona.com\\\/en\\\/event\\\/mwc-open-innovation-challenge-2024-dl-15-febrer\\\/\",\"url\":\"https:\\\/\\\/www.techbarcelona.com\\\/en\\\/event\\\/mwc-open-innovation-challenge-2024-dl-15-febrer\\\/\",\"name\":\"MWC Open Innovation Challenge 2024 (DL: 15 febrer) - Tech Barcelona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.techbarcelona.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.techbarcelona.com\\\/en\\\/event\\\/mwc-open-innovation-challenge-2024-dl-15-febrer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.techbarcelona.com\\\/en\\\/event\\\/mwc-open-innovation-challenge-2024-dl-15-febrer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.techbarcelona.com\\\/wp-content\\\/uploads\\\/image-821.jpeg\",\"datePublished\":\"2024-01-31T16:09:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.techbarcelona.com\\\/en\\\/event\\\/mwc-open-innovation-challenge-2024-dl-15-febrer\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.techbarcelona.com\\\/en\\\/event\\\/mwc-open-innovation-challenge-2024-dl-15-febrer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.techbarcelona.com\\\/en\\\/event\\\/mwc-open-innovation-challenge-2024-dl-15-febrer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.techbarcelona.com\\\/wp-content\\\/uploads\\\/image-821.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.techbarcelona.com\\\/wp-content\\\/uploads\\\/image-821.jpeg\",\"width\":720,\"height\":250},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.techbarcelona.com\\\/en\\\/event\\\/mwc-open-innovation-challenge-2024-dl-15-febrer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.techbarcelona.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/www.techbarcelona.com\\\/en\\\/event\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MWC Open Innovation Challenge 2024 (DL: 15 febrer)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.techbarcelona.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.techbarcelona.com\\\/en\\\/\",\"name\":\"Tech Barcelona\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.techbarcelona.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.techbarcelona.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.techbarcelona.com\\\/en\\\/#organization\",\"name\":\"Tech Barcelona\",\"url\":\"https:\\\/\\\/www.techbarcelona.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.techbarcelona.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.techbarcelona.com\\\/wp-content\\\/uploads\\\/logo-tech-bcn-black.png\",\"contentUrl\":\"https:\\\/\\\/www.techbarcelona.com\\\/wp-content\\\/uploads\\\/logo-tech-bcn-black.png\",\"width\":347,\"height\":90,\"caption\":\"Tech Barcelona\"},\"image\":{\"@id\":\"https:\\\/\\\/www.techbarcelona.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/BarcelonaTechCity\",\"https:\\\/\\\/x.com\\\/bcntechcity\",\"https:\\\/\\\/www.instagram.com\\\/bcntechcity\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/barcelona-tech-city\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCKX-ZX0pM37GRtVNKgr4Rxg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MWC Open Innovation Challenge 2024 (DL: 15 febrer) - Tech Barcelona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.techbarcelona.com\/en\/event\/mwc-open-innovation-challenge-2024-dl-15-febrer\/","og_locale":"en_US","og_type":"article","og_title":"MWC Open Innovation Challenge 2024 (DL: 15 febrer) - Tech Barcelona","og_url":"https:\/\/www.techbarcelona.com\/en\/event\/mwc-open-innovation-challenge-2024-dl-15-febrer\/","og_site_name":"Tech Barcelona","article_publisher":"https:\/\/www.facebook.com\/BarcelonaTechCity","twitter_card":"summary_large_image","twitter_site":"@bcntechcity","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.techbarcelona.com\/en\/event\/mwc-open-innovation-challenge-2024-dl-15-febrer\/","url":"https:\/\/www.techbarcelona.com\/en\/event\/mwc-open-innovation-challenge-2024-dl-15-febrer\/","name":"MWC Open Innovation Challenge 2024 (DL: 15 febrer) - Tech Barcelona","isPartOf":{"@id":"https:\/\/www.techbarcelona.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.techbarcelona.com\/en\/event\/mwc-open-innovation-challenge-2024-dl-15-febrer\/#primaryimage"},"image":{"@id":"https:\/\/www.techbarcelona.com\/en\/event\/mwc-open-innovation-challenge-2024-dl-15-febrer\/#primaryimage"},"thumbnailUrl":"https:\/\/www.techbarcelona.com\/wp-content\/uploads\/image-821.jpeg","datePublished":"2024-01-31T16:09:31+00:00","breadcrumb":{"@id":"https:\/\/www.techbarcelona.com\/en\/event\/mwc-open-innovation-challenge-2024-dl-15-febrer\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.techbarcelona.com\/en\/event\/mwc-open-innovation-challenge-2024-dl-15-febrer\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.techbarcelona.com\/en\/event\/mwc-open-innovation-challenge-2024-dl-15-febrer\/#primaryimage","url":"https:\/\/www.techbarcelona.com\/wp-content\/uploads\/image-821.jpeg","contentUrl":"https:\/\/www.techbarcelona.com\/wp-content\/uploads\/image-821.jpeg","width":720,"height":250},{"@type":"BreadcrumbList","@id":"https:\/\/www.techbarcelona.com\/en\/event\/mwc-open-innovation-challenge-2024-dl-15-febrer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.techbarcelona.com\/en\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/www.techbarcelona.com\/en\/event\/"},{"@type":"ListItem","position":3,"name":"MWC Open Innovation Challenge 2024 (DL: 15 febrer)"}]},{"@type":"WebSite","@id":"https:\/\/www.techbarcelona.com\/en\/#website","url":"https:\/\/www.techbarcelona.com\/en\/","name":"Tech Barcelona","description":"","publisher":{"@id":"https:\/\/www.techbarcelona.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.techbarcelona.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.techbarcelona.com\/en\/#organization","name":"Tech Barcelona","url":"https:\/\/www.techbarcelona.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.techbarcelona.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.techbarcelona.com\/wp-content\/uploads\/logo-tech-bcn-black.png","contentUrl":"https:\/\/www.techbarcelona.com\/wp-content\/uploads\/logo-tech-bcn-black.png","width":347,"height":90,"caption":"Tech Barcelona"},"image":{"@id":"https:\/\/www.techbarcelona.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BarcelonaTechCity","https:\/\/x.com\/bcntechcity","https:\/\/www.instagram.com\/bcntechcity\/","https:\/\/www.linkedin.com\/company\/barcelona-tech-city\/","https:\/\/www.youtube.com\/channel\/UCKX-ZX0pM37GRtVNKgr4Rxg"]}]}},"_links":{"self":[{"href":"https:\/\/www.techbarcelona.com\/en\/wp-json\/wp\/v2\/event\/68745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.techbarcelona.com\/en\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.techbarcelona.com\/en\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.techbarcelona.com\/en\/wp-json\/wp\/v2\/media\/68743"}],"wp:attachment":[{"href":"https:\/\/www.techbarcelona.com\/en\/wp-json\/wp\/v2\/media?parent=68745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}